{"id":5682,"date":"2023-11-30T13:21:47","date_gmt":"2023-11-30T13:21:47","guid":{"rendered":"https:\/\/serviceagricoleguillet.com\/?post_type=product&#038;p=5682"},"modified":"2023-11-30T13:21:47","modified_gmt":"2023-11-30T13:21:47","slug":"balise-b16-montage-permanent-12-24v-ambre","status":"publish","type":"product","link":"https:\/\/serviceagricoleguillet.com\/en\/produit\/balise-b16-montage-permanent-12-24v-ambre\/","title":{"rendered":"BALISE B16 - MONTAGE PERMANENT \/ 12-24V - AMBRE"},"content":{"rendered":"<ul>\n<li>Dot\u00e9 d\u2019une lentille anti-poussi\u00e8re, la balise Stroboscopique \u00e0 8 DEL B16<sup>MC<\/sup>\u00a0est id\u00e9al pour \u00eatre install\u00e9 sur les v\u00e9hicules de plus petite taille.<\/li>\n<li>Il est tr\u00e8s facile d\u2019entretien et son petit format est parfait pour les v\u00e9hicules avec un espace limit\u00e9. Le B16<sup>MC<\/sup>\u00a0r\u00e9pond aux normes SAE J845 Class I.<\/li>\n<\/ul>\n<p>FONCTIONNALIT\u00c9S<\/p>\n<ul>\n<li>Voltage d\u2019entr\u00e9e : 12 \u00e0 24Vdc<\/li>\n<li>11 s\u00e9quences de clignotements int\u00e9gr\u00e9es<\/li>\n<li>DEL \u00e0 haute intensit\u00e9 (8 DEL de 3 Watts)<\/li>\n<li>DEL \u00e0 dur\u00e9e de vie de 100 000 heures<\/li>\n<li>M\u00e9moire non volatile ce rappelle la derni\u00e8re s\u00e9quence utilis\u00e9 \u00e0 la mise sous tension<\/li>\n<li>Conception r\u00e9sistante aux intemp\u00e9ries et aux vibrations. Pour usage interne ou externe Disponible avec support magn\u00e9tique et adapteur pour prise allume-cigar ou montage permanent<\/li>\n<li>Protection contre l\u2019inversion de polarit\u00e9<\/li>\n<li>Plusieurs unit\u00e9s peuvent \u00eatre synchronis\u00e9es simultan\u00e9ment<\/li>\n<li>Couleur disponible : Ambre<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Dot\u00e9 d\u2019une lentille anti-poussi\u00e8re, la balise Stroboscopique \u00e0 8 DEL B16MC\u00a0est id\u00e9al pour \u00eatre install\u00e9 sur les v\u00e9hicules de plus petite taille. Il est tr\u00e8s facile d\u2019entretien et son petit format est parfait pour les v\u00e9hicules avec un espace limit\u00e9. Le B16MC\u00a0r\u00e9pond aux normes SAE J845 Class I. FONCTIONNALIT\u00c9S Voltage d\u2019entr\u00e9e : 12 \u00e0 24Vdc [&hellip;]<\/p>\n","protected":false},"featured_media":5685,"template":"","meta":{"_acf_changed":false,"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"both","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":""},"product_brand":[],"product_cat":[48],"product_tag":[],"class_list":["post-5682","product","type-product","status-publish","has-post-thumbnail","product_cat-eclairage","first","instock","taxable","shipping-taxable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/serviceagricoleguillet.com\/en\/wp-json\/wp\/v2\/product\/5682","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/serviceagricoleguillet.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/serviceagricoleguillet.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/serviceagricoleguillet.com\/en\/wp-json\/wp\/v2\/media\/5685"}],"wp:attachment":[{"href":"https:\/\/serviceagricoleguillet.com\/en\/wp-json\/wp\/v2\/media?parent=5682"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/serviceagricoleguillet.com\/en\/wp-json\/wp\/v2\/product_brand?post=5682"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/serviceagricoleguillet.com\/en\/wp-json\/wp\/v2\/product_cat?post=5682"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/serviceagricoleguillet.com\/en\/wp-json\/wp\/v2\/product_tag?post=5682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}